

{"id":894,"date":"2022-07-31T14:10:15","date_gmt":"2022-07-31T12:10:15","guid":{"rendered":"https:\/\/sagardeche.fr\/wordpress\/?page_id=894"},"modified":"2026-07-09T08:13:55","modified_gmt":"2026-07-09T06:13:55","slug":"accueil","status":"publish","type":"page","link":"https:\/\/sagardeche.fr\/wordpress\/","title":{"rendered":"Accueil"},"content":{"rendered":"<div data-colibri-id=\"894-c1\" class=\"style-447 style-local-894-c1 position-relative\">\n  <!---->\n  <div data-colibri-component=\"section\" data-colibri-id=\"894-c2\" id=\"custom\" class=\"h-section h-section-global-spacing d-flex align-items-lg-start align-items-md-start align-items-start style-448 style-local-894-c2 position-relative\">\n    <!---->\n    <!---->\n    <div class=\"h-section-grid-container h-section-boxed-container\">\n      <!---->\n      <div data-colibri-id=\"894-c3\" class=\"h-row-container gutters-row-lg-0 gutters-row-md-0 gutters-row-0 gutters-row-v-lg-0 gutters-row-v-md-0 gutters-row-v-0 style-563 style-local-894-c3 position-relative\">\n        <!---->\n        <div class=\"h-row justify-content-lg-center justify-content-md-center justify-content-center align-items-lg-stretch align-items-md-stretch align-items-stretch gutters-col-lg-0 gutters-col-md-0 gutters-col-0 gutters-col-v-lg-0 gutters-col-v-md-0 gutters-col-v-0\">\n          <!---->\n          <div class=\"h-column h-column-container d-flex h-col-lg-auto h-col-md-auto h-col-auto style-564-outer style-local-894-c4-outer\">\n            <div data-colibri-id=\"894-c4\" class=\"d-flex h-flex-basis h-column__inner h-px-lg-0 h-px-md-0 h-px-0 v-inner-lg-0 v-inner-md-0 v-inner-0 style-564 style-local-894-c4 position-relative\">\n              <!---->\n              <!---->\n              <div class=\"w-100 h-y-container h-column__content h-column__v-align flex-basis-100 align-self-lg-start align-self-md-start align-self-start\">\n                <!---->\n                <div data-colibri-id=\"894-c5\" class=\"h-x-container style-565 style-local-894-c5 position-relative h-element\">\n                  <!---->\n                  <div class=\"h-x-container-inner style-dynamic-894-c5-group style-565-spacing style-local-894-c5-spacing\"><span class=\"h-button__outer style-566-outer style-local-894-c6-outer d-inline-flex h-element\"><a h-use-smooth-scroll=\"true\" href=\"\/wordpress\/wp-login.php\"  data-colibri-id=\"894-c6\" class=\"d-flex w-100 align-items-center h-button justify-content-lg-center justify-content-md-center justify-content-center style-566 style-local-894-c6 position-relative\"><!----><!----> <span>Connexion<\/span><\/a>\n                    <\/span>\n                  <\/div>\n                <\/div>\n              <\/div>\n            <\/div>\n          <\/div>\n          <div class=\"h-column h-column-container d-flex h-col-lg-auto h-col-md-auto h-col-auto style-597-outer style-local-894-c7-outer\">\n            <div data-colibri-id=\"894-c7\" class=\"d-flex h-flex-basis h-column__inner h-px-lg-0 h-px-md-0 h-px-0 v-inner-lg-0 v-inner-md-0 v-inner-0 style-597 style-local-894-c7 position-relative\">\n              <!---->\n              <!---->\n              <div class=\"w-100 h-y-container h-column__content h-column__v-align flex-basis-100 align-self-lg-start align-self-md-start align-self-start\">\n                <!---->\n                <div data-colibri-id=\"894-c8\" class=\"h-x-container style-598 style-local-894-c8 position-relative h-element\">\n                  <!---->\n                  <div class=\"h-x-container-inner style-dynamic-894-c8-group style-598-spacing style-local-894-c8-spacing\"><span class=\"h-button__outer style-599-outer style-local-894-c9-outer d-inline-flex h-element\"><a h-use-smooth-scroll=\"true\" href=\"\/actes\"  data-colibri-id=\"894-c9\" class=\"d-flex w-100 align-items-center h-button justify-content-lg-center justify-content-md-center justify-content-center style-599 style-local-894-c9 position-relative\"><!----><!----> <span>Acc\u00e9der aux relev\u00e9s sur Expoactes<\/span><\/a>\n                    <\/span>\n                  <\/div>\n                <\/div>\n              <\/div>\n            <\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n      <div data-colibri-id=\"894-c10\" class=\"h-row-container gutters-row-lg-3 gutters-row-md-3 gutters-row-0 gutters-row-v-lg-3 gutters-row-v-md-3 gutters-row-v-3 style-449 style-local-894-c10 position-relative\">\n        <!---->\n        <div class=\"h-row justify-content-lg-center justify-content-md-center justify-content-center align-items-lg-stretch align-items-md-stretch align-items-stretch gutters-col-lg-3 gutters-col-md-3 gutters-col-0 gutters-col-v-lg-3 gutters-col-v-md-3 gutters-col-v-3\">\n          <!---->\n          <div class=\"h-column h-column-container d-flex h-col-lg-auto h-col-md-auto h-col-auto style-450-outer style-local-894-c11-outer\">\n            <div data-colibri-id=\"894-c11\" class=\"d-flex h-flex-basis h-column__inner h-px-lg-1 h-px-md-1 h-px-1 v-inner-lg-1 v-inner-md-1 v-inner-1 style-450 style-local-894-c11 position-relative\">\n              <!---->\n              <!---->\n              <div class=\"w-100 h-y-container h-column__content h-column__v-align flex-basis-100 align-self-lg-start align-self-md-start align-self-start\">\n                <!---->\n                <div data-colibri-id=\"894-c12\" class=\"h-text h-text-component style-452 style-local-894-c12 position-relative h-element\">\n                  <!---->\n                  <!---->\n                  <div class=\"\">\n                    <p>La SAGA est une association reconnue d&rsquo;utilit\u00e9 publique depuis 2013.<\/p>\n                    <p>En adh\u00e9rant \u00e0 la SAGA, vous acc\u00e9dez \u00e0 :<\/p>\n                    <ul>\n                      <li>Une base de donn\u00e9es augment\u00e9e, corrig\u00e9e et mise \u00e0 jour r\u00e9guli\u00e8rement comportant des actes de registres paroissiaux, catholiques et protestants, de l&rsquo;\u00e9tat-civil, de registres des notaires&#8230;<\/li>\n                    <\/ul>\n                    <p><span style=\"color: rgb(9, 33, 42); font-family: &quot;Open Sans&quot;; font-size: 16px; font-weight: 400;\">&nbsp;Actuellement notre base de donn\u00e9es compte&nbsp;&nbsp;<b>5096069 actes<\/b>\r\n<\/span><\/p>\n                    <ul>\n                      <li>Des r\u00e9f\u00e9rences des actes des personnes n\u00e9es ou d\u00e9c\u00e9d\u00e9es en Ard\u00e8che depuis 1970 (Sources INSEE&#8230;)<\/li>\n                      <li><span style=\"font-weight: 400; font-size: 14px; font-family: Arial, sans-serif; color: rgb(51, 51, 51);\">Plus de 40 000 photos d&rsquo;actes num\u00e9ris\u00e9s non disponibles aux AD07<\/span><\/li>\n                      <li>Une recherche rapide, simple et efficace.<span style=\"font-weight: 400; font-size: 14px; font-family: Arial, sans-serif; color: rgb(51, 51, 51);\">&nbsp;<\/span><\/li>\n                      <li>Un lien direct pointant sur l&rsquo;acte recherch\u00e9.<\/li>\n                      <li>Un forum ouvert aux adh\u00e9rents SAGA.<\/li>\n                    <\/ul>\n                    <p>Cr\u00e9\u00e9e en 1989, la SAGA, forte de ses 35 ann\u00e9es d&rsquo;exp\u00e9rience et de ses 1000 adh\u00e9rents, est devenue au fil des ann\u00e9es un acteur incontournable pour la sauvegarde et la diffusion des documents anciens.<\/p>\n                    <p>En effet, plusieurs conventions de partenariat avec le d\u00e9partement de l&rsquo;Ard\u00e8che, les Archives d\u00e9partementales et le Dioc\u00e8se de Viviers permettent \u00e0 la SAGA de num\u00e9riser ces ouvrages s\u00e9culaires. Cette production est mise gratuitement\n                      \u00e0 disposition du public sur le site Internet des Archives d\u00e9partementales de l&rsquo;Ard\u00e8che.<\/p>\n                    <p>Tous les actes pr\u00e9sents dans ces registres anciens (BMS* catholiques et protestants, NMD** de l\u2019\u00c9tat civil, actes des notaires&#8230;) sont r\u00e9pertori\u00e9s et valoris\u00e9s par les b\u00e9n\u00e9voles de la SAGA sous forme d&rsquo;une immense base de donn\u00e9es\n                      accessible \u00e0 ses adh\u00e9rents. Ce gigantesque travail se poursuit sans rel\u00e2che. Pourquoi ne pas rejoindre cette \u00e9quipe en devenant vous-m\u00eame b\u00e9n\u00e9voles ?<\/p>\n                    <p>En vous rendant au local SAGA \u00e0 Chom\u00e9rac, vous pourrez consulter les 3000 registres de la biblioth\u00e8que accessible aux adh\u00e9rents sur rendez-vous mardi et mercredi apr\u00e8s-midi et vendredi matin.<\/p>\n                    <p>Bonne navigation !<\/p>\n                    <p>* Bapt\u00eame, Mariage, S\u00e9pulture **Naissance, Mariage, D\u00e9c\u00e8s<\/p>\n                  <\/div>\n                <\/div>\n              <\/div>\n            <\/div>\n          <\/div>\n          <div class=\"h-column h-column-container d-flex h-col-lg-auto h-col-md-auto h-col-auto style-451-outer style-local-894-c13-outer\">\n            <div data-colibri-id=\"894-c13\" class=\"d-flex h-flex-basis h-column__inner h-px-lg-1 h-px-md-1 h-px-1 v-inner-lg-1 v-inner-md-1 v-inner-1 style-451 style-local-894-c13 position-relative\">\n              <!---->\n              <!---->\n              <div class=\"w-100 h-y-container h-column__content h-column__v-align flex-basis-100 align-self-lg-start align-self-md-start align-self-start\">\n                <!---->\n                <div data-colibri-id=\"894-c14\" class=\"h-text h-text-component style-592 style-local-894-c14 position-relative h-element\">\n                  <!---->\n                  <!---->\n                  <div class=\"\">\n                    <p>Actualit\u00e9s<\/p>\n                  <\/div>\n                <\/div>\n                <div data-colibri-id=\"894-c15\" class=\"h-global-transition-all h-heading style-705 style-local-894-c15 position-relative h-element\">\n                  <!---->\n                  <div class=\"h-heading__outer style-705 style-local-894-c15\">\n                    <!---->\n                    <!---->\n                    <a href=\"https:\/\/archives.ardeche.fr\/data\/20260608_nouveaux_registres_notaires_numerises.pdf\" h-use-smooth-scroll=\"true\">\n                      <h5 class=\"\">109 nouveaux registres de notaires num\u00e9ris\u00e9s mis en ligne<\/h5>\n                    <\/a>\n                  <\/div>\n                <\/div>\n                <div data-colibri-id=\"894-c16\" class=\"h-text h-text-component style-699 style-local-894-c16 position-relative h-element\">\n                  <!---->\n                  <!---->\n                  <div class=\"\">\n                    <p>Les Archives d\u00e9partementales de l\u2019Ard\u00e8che viennent de mettre en ligne 109 nouveaux registres de notaires num\u00e9ris\u00e9s par la SAGA. Les donn\u00e9es issues de ces registres viennent d&rsquo;\u00eatre int\u00e9gr\u00e9es \u00e0 notre base de donn\u00e9es. Un grand merci aux\n                      b\u00e9n\u00e9voles de la SAGA pour cet immense travail d&rsquo;indexation.<\/p>\n                  <\/div>\n                <\/div>\n                <div data-colibri-id=\"894-c17\" class=\"h-x-container style-701 style-local-894-c17 position-relative h-element\">\n                  <!---->\n                  <div class=\"h-x-container-inner style-dynamic-894-c17-group style-701-spacing style-local-894-c17-spacing\"><span class=\"h-link__outer style-702-outer style-local-894-c18-outer d-inline-flex h-element\"><a h-use-smooth-scroll=\"true\" href=\"https:\/\/archives.ardeche.fr\/data\/20260608_nouveaux_registres_notaires_numerises.pdf\"  data-colibri-id=\"894-c18\" class=\"d-flex w-100 align-items-center h-link style-702 style-local-894-c18 position-relative\"><!----><!----> <span>Nouveaux registres mis en ligne<\/span><\/a>\n                    <\/span>\n                  <\/div>\n                <\/div>\n                <div data-colibri-id=\"894-c19\" class=\"h-divider style-704 style-local-894-c19 position-relative h-element\">\n                  <!----><span class=\"h-divider__line style-704-line style-local-894-c19-line style-704-line style-local-894-c19-line\"><\/span><\/div>\n                <div data-colibri-id=\"894-c20\" class=\"h-text h-text-component style-712 style-local-894-c20 position-relative h-element\">\n                  <!---->\n                  <!---->\n                  <div class=\"\">\n                    <p><span style=\"font-family: Arial, sans-serif;\">A<\/span><span style=\"font-family: Arial, sans-serif; color: rgb(68, 114, 196);\">&nbsp;<\/span><span style=\"font-family: Arial, sans-serif;\">l\u2019occasion du centenaire de la Carte du Combattant, l&rsquo;Office Nationale des Combattants et des victimes de Guerre lance un appel \u00e0 participation afin de retrouver des cartes du combattant de toutes ann\u00e9es et de tous d\u00e9partements. Nous vous invitons \u00e0 d\u00e9couvrir l\u2019affiche (cliquez sur l&rsquo;image ci-dessous) et \u00e0 la diffuser largement autour de vous : famille, amis ; coll\u00e8gues, voisins, adh\u00e9rents, connaissances\u2026 Une carte se trouve peut-\u00eatre au fond d\u2019un tiroir, dans une bo\u00eete de souvenirs, un portefeuille ou parmi des papiers de famille\u2026<\/span><\/p>\n                  <\/div>\n                <\/div>\n                <div data-colibri-id=\"894-c21\" class=\"d-block style-711 style-local-894-c21 position-relative h-element\">\n                  <!---->\n                  <div class=\"h-image__frame-container-outer\">\n                    <a href=\"https:\/\/sagardeche.fr\/wordpress\/wp-content\/uploads\/2026\/07\/100-ANS-CARTE-DU-COMBATTANT-1.pdf\" h-use-smooth-scroll=\"true\" class=\"image-link\">\n                      <div class=\"h-image__frame-container\">\n                        <!---->\n                        <!---->\n                        <img decoding=\"async\" src=\"https:\/\/sagardeche.fr\/wordpress\/wp-content\/uploads\/2026\/07\/cropped-1783323626550-30950fa1-26b9-4701-9f1f-cc160594f935_1-211x300.jpg\" class=\"style-711-image style-local-894-c21-image\">\n                        <div class=\"h-image__frame h-hide-lg h-hide-md h-hide-sm style-711-frameImage style-local-894-c21-frameImage\"><\/div>\n                      <\/div>\n                    <\/a>\n                  <\/div>\n                <\/div>\n                <div data-colibri-id=\"894-c22\" class=\"h-divider style-714 style-local-894-c22 position-relative h-element\">\n                  <!----><span class=\"h-divider__line style-714-line style-local-894-c22-line style-714-line style-local-894-c22-line\"><\/span><\/div>\n                <div data-colibri-id=\"894-c23\" class=\"h-global-transition-all h-heading style-708 style-local-894-c23 position-relative h-element\">\n                  <!---->\n                  <div class=\"h-heading__outer style-708 style-local-894-c23\">\n                    <!---->\n                    <!---->\n                    <h6 class=\"\">Mise en ligne des registres matricules militaires des classes 1922 \u00e0 1925.<\/h6>\n                  <\/div>\n                <\/div>\n                <div data-colibri-id=\"894-c24\" class=\"h-text h-text-component style-707 style-local-894-c24 position-relative h-element\">\n                  <!---->\n                  <!---->\n                  <div class=\"\">\n                    <p>Les fiches matricules des conscrits ard\u00e9chois appartenant aux classes 1922 \u00e0 1925 sont d\u00e9sormais consultables sur le site des Archives d\u00e9partementales. Elles viennent compl\u00e9ter les fiches d\u00e9j\u00e0 accessibles en ligne des classes 1867\n                      \u00e0 1921.<\/p>\n                  <\/div>\n                <\/div>\n                <div data-colibri-id=\"894-c25\" class=\"h-divider style-710 style-local-894-c25 position-relative h-element\">\n                  <!----><span class=\"h-divider__line style-710-line style-local-894-c25-line style-710-line style-local-894-c25-line\"><\/span><\/div>\n                <div data-colibri-id=\"894-c26\" class=\"h-text h-text-component style-594 style-local-894-c26 position-relative h-element\">\n                  <!---->\n                  <!---->\n                  <div class=\"\">\n                    <p>Derni\u00e8res mises \u00e0 jour<\/p>\n                  <\/div>\n                <\/div>\n                <div data-colibri-id=\"894-c27\" class=\"h-text h-text-component style-567 style-local-894-c27 position-relative h-element\">\n                  <!---->\n                  <!---->\n                  <div class=\"\">\n                    <li><a href='https:\/\/sagardeche.fr\/wordpress\/index.php\/application-android-saga\/'>Application Andro\u00efd SAGA<\/a><\/li><li><a href='https:\/\/sagardeche.fr\/wordpress\/index.php\/intelligence-artificielle-et-genealogie\/'>Intelligence Artificielle et g\u00e9n\u00e9alogie<\/a><\/li><li><a href='https:\/\/sagardeche.fr\/wordpress\/index.php\/les-mariages-des-pasteurs-en-vivarais-1721-1757\/'>Les mariages des pasteurs en Vivarais (1721-1757)<\/a><\/li><li><a href='https:\/\/sagardeche.fr\/wordpress\/index.php\/adhesion-saga-v3\/'>Adh\u00e9sion \u00e0 la Saga<\/a><\/li><li><a href='https:\/\/sagardeche.fr\/wordpress\/index.php\/rechercher-dans-expoactes\/'>Mode d&#8217;emploi : rechercher dans Expoactes<\/a><\/li>        \r\n\n                  <\/div>\n                <\/div>\n                <div data-colibri-id=\"894-c28\" class=\"h-text h-text-component style-595 style-local-894-c28 position-relative h-element\">\n                  <!---->\n                  <!---->\n                  <div class=\"\">\n                    <p><em style=\"color: rgb(70, 112, 127); font-family: &quot;Open Sans&quot;; font-size: 19.2px; font-weight: 600;\">Derniers imports de donn\u00e9es<\/em><\/p>\n                  <\/div>\n                <\/div>\n                <div data-colibri-id=\"894-c29\" class=\"h-text h-text-component style-596 style-local-894-c29 position-relative h-element\">\n                  <!---->\n                  <!---->\n                  <div class=\"\">\n                    <p><span style=\"font-weight: 400; font-size: 16px; font-family: &quot;Open Sans&quot;; color: rgb(70, 112, 127);\"><li><a href=\/actes\/tab_bans.php?args=Saint-Barth%C3%A9lemy-le-Plain%0D%0A%5BArd%C3%A8che%5D>Saint-Barth\u00e9lemy-le-Plain (Ard\u00e8che) 328 actes de 1812 \u00e0\r\n1822<\/a><li><a href=\/actes\/tab_bans.php?args=Saint-Barth%C3%A9lemy-le-Plain%0D%0A%5BArd%C3%A8che%5D>Saint-Barth\u00e9lemy-le-Plain (Ard\u00e8che) 284 actes de 1803 \u00e0\r\n1822<\/a><li><a href=\/actes\/tab_bans.php?args=Saint-Genest-Lachamp%0D%0A%5BArd%C3%A8che%5D>Saint-Genest-Lachamp (Ard\u00e8che) 1966 actes de 1608 \u00e0\r\n1902<\/a><li><a href=\/actes\/tab_bans.php?args=Saint-Barth%C3%A9lemy-le-Plain%0D%0A%5BArd%C3%A8che%5D>Saint-Barth\u00e9lemy-le-Plain (Ard\u00e8che) 997 actes de 1802 \u00e0\r\n1922<\/a><li><a href=\/actes\/tab_bans.php?args=Lanas%0D%0A%5BArd%C3%A8che%5D>Lanas (Ard\u00e8che) 96 actes de 1610 \u00e0\r\n1753<\/a>\r\n<\/span><\/p>\n                  <\/div>\n                <\/div>\n              <\/div>\n            <\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n  <div data-colibri-component=\"section\" data-colibri-id=\"894-c30\" id=\"custom-2\" class=\"h-section h-section-global-spacing d-flex align-items-lg-center align-items-md-center align-items-center style-458 style-local-894-c30 position-relative\">\n    <!---->\n    <!---->\n    <div class=\"h-section-grid-container h-section-boxed-container\">\n      <!---->\n      <div data-colibri-id=\"894-c31\" class=\"h-row-container gutters-row-lg-2 gutters-row-md-2 gutters-row-0 gutters-row-v-lg-2 gutters-row-v-md-2 gutters-row-v-2 style-459 style-local-894-c31 position-relative\">\n        <!---->\n        <div class=\"h-row justify-content-lg-center justify-content-md-center justify-content-center align-items-lg-stretch align-items-md-stretch align-items-stretch gutters-col-lg-2 gutters-col-md-2 gutters-col-0 gutters-col-v-lg-2 gutters-col-v-md-2 gutters-col-v-2\">\n          <!---->\n          <div class=\"h-column h-column-container d-flex h-col-lg-auto h-col-md-auto h-col-auto style-460-outer style-local-894-c32-outer\">\n            <div data-colibri-id=\"894-c32\" class=\"d-flex h-flex-basis h-column__inner h-px-lg-2 h-px-md-2 h-px-2 v-inner-lg-2 v-inner-md-2 v-inner-2 style-460 style-local-894-c32 position-relative\">\n              <!---->\n              <!---->\n              <div class=\"w-100 h-y-container h-column__content h-column__v-align flex-basis-100 align-self-lg-start align-self-md-start align-self-start\">\n                <!---->\n                <div data-colibri-id=\"894-c33\" class=\"h-text h-text-component style-469 style-local-894-c33 position-relative h-element\">\n                  <!---->\n                  <!---->\n                  <div class=\"\">\n                    \n\n\t\t\t\t<div id=\"map_ol3js_1\" class=\"map undefined\" data-map_name=\"undefined\" data-map=\"map_ol3js_1\" style=\"width:100%; max-width:100%; height:450px; display:block; overflow:hidden;border:2px solid grey;\" >\n\t\t\t\t  <div id=\"map_ol3js_1_popup\" class=\"ol-popup\" >\n\t\t\t\t\t<a href=\"#\" id=\"map_ol3js_1_popup-closer\" class=\"ol-popup-closer\"><\/a>\n\t\t\t\t\t<div id=\"map_ol3js_1_popup-content\" ><\/div>\n\t\t\t\t  <\/div>\n\t\t\t\t<\/div>\n\t\t\t\n\n\t\t\t\t<script type=\"text\/javascript\">\n\t\t\t\t\ttranslations['openlayer'] = \"open layer\";\n\t\t\t\t\ttranslations['openlayerAtStartup'] = \"open layer at startup\";\n\t\t\t\t\ttranslations['generateLink'] = \"link to this map with opened layers\";\n\t\t\t\t\ttranslations['shortDescription'] = \"short description\";\n\t\t\t\t\ttranslations['generatedShortCode'] = \"to get a text control link paste this code in your wordpress editor\";\n\t\t\t\t\ttranslations['closeLayer'] = \"close layer\";\n\t\t\t\t\ttranslations['cantGenerateLink'] = \"put this string in the existing map short code to control this map\";\n\t\t\t  <\/script>\n\n\n\t\t\t  <script type=\"text\/javascript\">\n\t\t\t  vectorM['map_ol3js_1'] = [];\n\t        \n        var raster = getTileLayer(\"osm\",\"NoKey\");\t\t\t\n\n\t\t\t  var map_ol3js_1 = new ol.Map({\n\t\t\t\tinteractions: ol.interaction.defaults.defaults({mouseWheelZoom:false}),\n\t\t\t\tlayers: [raster],\n\t\t\t\ttarget: \"map_ol3js_1\",\n\t\t\t\tview: new ol.View({\n\t\t\t\t  center: ol.proj.transform([4.6594,44.7072], \"EPSG:4326\", \"EPSG:3857\"),\n\t\t\t\t  zoom: 12\n\t\t\t\t})\n\t\t\t  });\n\t\t\t  addControls2Map(map_ol3js_1,0,0,3,0,5,6,7,1,1);\nosm_addPopupClickhandler(map_ol3js_1,  \"map_ol3js_1\"); \nosm_addMouseHover(map_ol3js_1); <\/script>\n                  <\/div>\n                <\/div>\n              <\/div>\n            <\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n  <div data-colibri-component=\"section\" data-colibri-id=\"894-c34\" id=\"custom-3\" class=\"h-section h-section-global-spacing d-flex align-items-lg-center align-items-md-center align-items-center style-503 style-local-894-c34 position-relative\">\n    <!---->\n    <!---->\n    <div class=\"h-section-grid-container h-section-boxed-container\">\n      <!---->\n      <div data-colibri-id=\"894-c35\" class=\"h-row-container gutters-row-lg-2 gutters-row-md-2 gutters-row-0 gutters-row-v-lg-2 gutters-row-v-md-2 gutters-row-v-2 style-504 style-local-894-c35 position-relative\">\n        <!---->\n        <div class=\"h-row justify-content-lg-center justify-content-md-center justify-content-center align-items-lg-stretch align-items-md-stretch align-items-stretch gutters-col-lg-2 gutters-col-md-2 gutters-col-0 gutters-col-v-lg-2 gutters-col-v-md-2 gutters-col-v-2\">\n          <!---->\n          <div class=\"h-column h-column-container d-flex h-col-lg-auto h-col-md-auto h-col-auto style-505-outer style-local-894-c36-outer\">\n            <div data-colibri-id=\"894-c36\" class=\"d-flex h-flex-basis h-column__inner h-px-lg-2 h-px-md-2 h-px-2 v-inner-lg-2 v-inner-md-2 v-inner-2 style-505 style-local-894-c36 position-relative\">\n              <!---->\n              <!---->\n              <div class=\"w-100 h-y-container h-column__content h-column__v-align flex-basis-100 align-self-lg-start align-self-md-start align-self-start\">\n                <!---->\n                <div data-colibri-id=\"894-c37\" class=\"h-x-container style-506 style-local-894-c37 position-relative h-element\">\n                  <!---->\n                  <div class=\"h-x-container-inner style-dynamic-894-c37-group style-506-spacing style-local-894-c37-spacing\"><span class=\"h-link__outer style-507-outer style-local-894-c38-outer d-inline-flex h-element\"><a h-use-smooth-scroll=\"true\" href=\"https:\/\/sagardeche.fr\/wordpress\/index.php\/mentions-legales\/\" target=\"_blank\"  data-colibri-id=\"894-c38\" class=\"d-flex w-100 align-items-center h-link style-507 style-local-894-c38 position-relative\"><!----><!----> <span>Mentions L\u00e9gales<\/span><\/a>\n                    <\/span>\n                  <\/div>\n                <\/div>\n              <\/div>\n            <\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Connexion Acc\u00e9der aux relev\u00e9s sur Expoactes La SAGA est une association reconnue d&rsquo;utilit\u00e9 publique depuis 2013. En adh\u00e9rant \u00e0 la SAGA, vous acc\u00e9dez \u00e0 : Une base de donn\u00e9es augment\u00e9e, corrig\u00e9e et mise \u00e0 jour r\u00e9guli\u00e8rement comportant des actes de registres paroissiaux, catholiques et protestants, de l&rsquo;\u00e9tat-civil, de registres des notaires&#8230; &nbsp;Actuellement notre base de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/full-width-page.php","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-894","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Accueil - SagArdeche<\/title>\n<meta name=\"description\" content=\"Accueil SagArdeche Soci\u00e9t\u00e9 amateurs g\u00e9n\u00e9alogie Ard\u00e8che Registres BMS Notaires paroissiaux Origines Ard\u00e9choises expoactes saga protestants\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sagardeche.fr\/wordpress\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Accueil - SagArdeche\" \/>\n<meta property=\"og:description\" content=\"Accueil SagArdeche Soci\u00e9t\u00e9 amateurs g\u00e9n\u00e9alogie Ard\u00e8che Registres BMS Notaires paroissiaux Origines Ard\u00e9choises expoactes saga protestants\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sagardeche.fr\/wordpress\/\" \/>\n<meta property=\"og:site_name\" content=\"SagArdeche\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/geneardeche\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-09T06:13:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sagardeche.fr\/wordpress\/wp-content\/uploads\/2026\/07\/cropped-1783323626550-30950fa1-26b9-4701-9f1f-cc160594f935_1-211x300.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sagardeche.fr\/wordpress\/\",\"url\":\"https:\/\/sagardeche.fr\/wordpress\/\",\"name\":\"Accueil - SagArdeche\",\"isPartOf\":{\"@id\":\"https:\/\/sagardeche.fr\/wordpress\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sagardeche.fr\/wordpress\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sagardeche.fr\/wordpress\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sagardeche.fr\/wordpress\/wp-content\/uploads\/2026\/07\/cropped-1783323626550-30950fa1-26b9-4701-9f1f-cc160594f935_1-211x300.jpg\",\"datePublished\":\"2022-07-31T12:10:15+00:00\",\"dateModified\":\"2026-07-09T06:13:55+00:00\",\"description\":\"Accueil SagArdeche Soci\u00e9t\u00e9 amateurs g\u00e9n\u00e9alogie Ard\u00e8che Registres BMS Notaires paroissiaux Origines Ard\u00e9choises expoactes saga protestants\",\"breadcrumb\":{\"@id\":\"https:\/\/sagardeche.fr\/wordpress\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sagardeche.fr\/wordpress\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/sagardeche.fr\/wordpress\/#primaryimage\",\"url\":\"https:\/\/sagardeche.fr\/wordpress\/wp-content\/uploads\/2026\/07\/cropped-1783323626550-30950fa1-26b9-4701-9f1f-cc160594f935_1.jpg\",\"contentUrl\":\"https:\/\/sagardeche.fr\/wordpress\/wp-content\/uploads\/2026\/07\/cropped-1783323626550-30950fa1-26b9-4701-9f1f-cc160594f935_1.jpg\",\"width\":721,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sagardeche.fr\/wordpress\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/sagardeche.fr\/wordpress\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Accueil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sagardeche.fr\/wordpress\/#website\",\"url\":\"https:\/\/sagardeche.fr\/wordpress\/\",\"name\":\"SagArdeche\",\"description\":\"Soci\u00e9t\u00e9 des Amateurs de G\u00e9n\u00e9alogie de l&#039;Ard\u00e8che\",\"publisher\":{\"@id\":\"https:\/\/sagardeche.fr\/wordpress\/#organization\"},\"alternateName\":\"saga\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sagardeche.fr\/wordpress\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sagardeche.fr\/wordpress\/#organization\",\"name\":\"Soci\u00e9t\u00e9 des Amateurs de G\u00e9n\u00e9alogie de l'Ard\u00e8che\",\"alternateName\":\"SAGA\",\"url\":\"https:\/\/sagardeche.fr\/wordpress\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/sagardeche.fr\/wordpress\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sagardeche.fr\/wordpress\/wp-content\/uploads\/2022\/06\/cropped-LogoSAGA3-1.jpg\",\"contentUrl\":\"https:\/\/sagardeche.fr\/wordpress\/wp-content\/uploads\/2022\/06\/cropped-LogoSAGA3-1.jpg\",\"width\":50,\"height\":80,\"caption\":\"Soci\u00e9t\u00e9 des Amateurs de G\u00e9n\u00e9alogie de l'Ard\u00e8che\"},\"image\":{\"@id\":\"https:\/\/sagardeche.fr\/wordpress\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/geneardeche\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Accueil - SagArdeche","description":"Accueil SagArdeche Soci\u00e9t\u00e9 amateurs g\u00e9n\u00e9alogie Ard\u00e8che Registres BMS Notaires paroissiaux Origines Ard\u00e9choises expoactes saga protestants","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sagardeche.fr\/wordpress\/","og_locale":"fr_FR","og_type":"article","og_title":"Accueil - SagArdeche","og_description":"Accueil SagArdeche Soci\u00e9t\u00e9 amateurs g\u00e9n\u00e9alogie Ard\u00e8che Registres BMS Notaires paroissiaux Origines Ard\u00e9choises expoactes saga protestants","og_url":"https:\/\/sagardeche.fr\/wordpress\/","og_site_name":"SagArdeche","article_publisher":"https:\/\/www.facebook.com\/geneardeche","article_modified_time":"2026-07-09T06:13:55+00:00","og_image":[{"url":"https:\/\/sagardeche.fr\/wordpress\/wp-content\/uploads\/2026\/07\/cropped-1783323626550-30950fa1-26b9-4701-9f1f-cc160594f935_1-211x300.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sagardeche.fr\/wordpress\/","url":"https:\/\/sagardeche.fr\/wordpress\/","name":"Accueil - SagArdeche","isPartOf":{"@id":"https:\/\/sagardeche.fr\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sagardeche.fr\/wordpress\/#primaryimage"},"image":{"@id":"https:\/\/sagardeche.fr\/wordpress\/#primaryimage"},"thumbnailUrl":"https:\/\/sagardeche.fr\/wordpress\/wp-content\/uploads\/2026\/07\/cropped-1783323626550-30950fa1-26b9-4701-9f1f-cc160594f935_1-211x300.jpg","datePublished":"2022-07-31T12:10:15+00:00","dateModified":"2026-07-09T06:13:55+00:00","description":"Accueil SagArdeche Soci\u00e9t\u00e9 amateurs g\u00e9n\u00e9alogie Ard\u00e8che Registres BMS Notaires paroissiaux Origines Ard\u00e9choises expoactes saga protestants","breadcrumb":{"@id":"https:\/\/sagardeche.fr\/wordpress\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sagardeche.fr\/wordpress\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sagardeche.fr\/wordpress\/#primaryimage","url":"https:\/\/sagardeche.fr\/wordpress\/wp-content\/uploads\/2026\/07\/cropped-1783323626550-30950fa1-26b9-4701-9f1f-cc160594f935_1.jpg","contentUrl":"https:\/\/sagardeche.fr\/wordpress\/wp-content\/uploads\/2026\/07\/cropped-1783323626550-30950fa1-26b9-4701-9f1f-cc160594f935_1.jpg","width":721,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/sagardeche.fr\/wordpress\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/sagardeche.fr\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Accueil"}]},{"@type":"WebSite","@id":"https:\/\/sagardeche.fr\/wordpress\/#website","url":"https:\/\/sagardeche.fr\/wordpress\/","name":"SagArdeche","description":"Soci\u00e9t\u00e9 des Amateurs de G\u00e9n\u00e9alogie de l&#039;Ard\u00e8che","publisher":{"@id":"https:\/\/sagardeche.fr\/wordpress\/#organization"},"alternateName":"saga","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sagardeche.fr\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/sagardeche.fr\/wordpress\/#organization","name":"Soci\u00e9t\u00e9 des Amateurs de G\u00e9n\u00e9alogie de l'Ard\u00e8che","alternateName":"SAGA","url":"https:\/\/sagardeche.fr\/wordpress\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sagardeche.fr\/wordpress\/#\/schema\/logo\/image\/","url":"https:\/\/sagardeche.fr\/wordpress\/wp-content\/uploads\/2022\/06\/cropped-LogoSAGA3-1.jpg","contentUrl":"https:\/\/sagardeche.fr\/wordpress\/wp-content\/uploads\/2022\/06\/cropped-LogoSAGA3-1.jpg","width":50,"height":80,"caption":"Soci\u00e9t\u00e9 des Amateurs de G\u00e9n\u00e9alogie de l'Ard\u00e8che"},"image":{"@id":"https:\/\/sagardeche.fr\/wordpress\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/geneardeche"]}]}},"_links":{"self":[{"href":"https:\/\/sagardeche.fr\/wordpress\/index.php\/wp-json\/wp\/v2\/pages\/894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sagardeche.fr\/wordpress\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sagardeche.fr\/wordpress\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sagardeche.fr\/wordpress\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sagardeche.fr\/wordpress\/index.php\/wp-json\/wp\/v2\/comments?post=894"}],"version-history":[{"count":20,"href":"https:\/\/sagardeche.fr\/wordpress\/index.php\/wp-json\/wp\/v2\/pages\/894\/revisions"}],"predecessor-version":[{"id":4067,"href":"https:\/\/sagardeche.fr\/wordpress\/index.php\/wp-json\/wp\/v2\/pages\/894\/revisions\/4067"}],"wp:attachment":[{"href":"https:\/\/sagardeche.fr\/wordpress\/index.php\/wp-json\/wp\/v2\/media?parent=894"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sagardeche.fr\/wordpress\/index.php\/wp-json\/wp\/v2\/categories?post=894"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sagardeche.fr\/wordpress\/index.php\/wp-json\/wp\/v2\/tags?post=894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}